{"id":1129,"date":"2015-06-15T10:56:44","date_gmt":"2015-06-15T08:56:44","guid":{"rendered":"http:\/\/iflw.de\/blog\/?p=1129"},"modified":"2020-04-23T10:47:07","modified_gmt":"2020-04-23T08:47:07","slug":"hochbegabte-in-der-lerntherapie-anlaesse-und-foerderansaetze","status":"publish","type":"post","link":"https:\/\/www.iflw.de\/blog\/hochbegabung\/hochbegabte-in-der-lerntherapie-anlaesse-und-foerderansaetze\/","title":{"rendered":"Hochbegabte in der Lerntherapie: Anl\u00e4sse und F\u00f6rderans\u00e4tze"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Lesen Sie in diesem Blog-Beitrag, was unter\u00a0Hochbegabung verstanden wird, warum manche hochbegabte Kinder und Jugendliche einen\u00a0lerntherapeutischen F\u00f6rderbedarf haben und welche F\u00f6rderans\u00e4tze f\u00fcr Hochbegabte in der\u00a0Lerntherapie geeignet sind.<\/em><\/p>\n<p>Hochbegabte in der Lerntherapie? F\u00fcr viele ist das ein Widerspruch. Zu verbreitet ist das Bild vom\u00a0bebrillten \u00dcberflieger, der jede schulische Anforderung mit Leichtigkeit meistert und in der Freizeit\u00a0virtuos Geige, Schach und Tennis spielt. Wer aber aufgrund von Lern- und\u00a0Leistungsschwierigkeiten eine Lerntherapie in Anspruch nimmt, der kann doch unm\u00f6glich einen\u00a0hohen IQ haben, so die landl\u00e4ufige Meinung.<\/p>\n<h2>Wo beginnt Hochbegabung?<\/h2>\n<p>Wer in einem Intelligenztest einen IQ (Intelligenzquotienten) von \u00fcber 130 erzielt, gilt als intellektuell hochbegabt. In den IQ-Wert k\u00f6nnen jedoch nur die in der Testsituation gezeigten intellektuellen F\u00e4higkeiten einflie\u00dfen. Ist der Getestete w\u00e4hrend des Tests nicht ganz bei der Sache, so steht am Ende ein IQ, der unterhalb des wahren Potenzials des Kindes, Jugendlichen oder Erwachsenen liegt. In diesem Fall kann ein weiterer Intelligenztest mit einem anderen oder demselben Verfahren sinnvoll sein. Jedoch f\u00fchren Nachtestungen zu Trainingseffekten, die ihrerseits das Ergebnis verf\u00e4lschen, dann aber in Richtung eines h\u00f6heren Wertes. Wichtig zu wissen ist, dass der IQ nur ein Testergebnis ist und dass dieser Wert und auch die intellektuellen F\u00e4higkeiten eines Menschen mit Training verbessert werden k\u00f6nnen.<\/p>\n<h2>Schwierigkeiten hochbegabter Kinder<\/h2>\n<h3>Asynchrone Entwicklung<\/h3>\n<p>Die Entwicklung von hochbegabten Kindern verl\u00e4uft in der Regel asynchron. Das bedeutet, dass sich mehrere F\u00e4higkeiten nicht in der gleichen Geschwindigkeit entwickeln. Hochbegabte Kinder sind intellektuell weit voraus, aber emotional und sozial meist altersgerecht entwickelt. Sie sind schon fr\u00fch zu abstrakten Denkleistungen in der Lage, beeindrucken mit erstaunlichen Ein- und Ansichten, philosophieren \u00fcber den Sinn des Lebens, k\u00f6nnen aber wegen einer versagten S\u00fc\u00dfigkeit genauso schnell in Tr\u00e4nen ausbrechen wie andere Kinder gleichen Alters. Viele hochbegabte Kinder bevorzugen \u00e4ltere und damit intellektuell ebenb\u00fcrtige Kinder als Gespr\u00e4chs- und Spielpartner. Jedoch werden sie von diesen aufgrund ihres noch kindlichen Verhaltens oft ausgegrenzt. Auch deshalb haben hochbegabte Kinder h\u00e4ufig das Gef\u00fchl, nirgends richtig dazu zu geh\u00f6ren.<\/p>\n<h3>Verstecken von Begabungen<\/h3>\n<p>Die meisten Menschen und insbesondere Kinder sehnen sich nach Gemeinschaft und Anerkennung. Hochbegabte Kinder machen manchmal die Erfahrung, dass ihr Naturell den Kontakt zu m\u00f6glichen Spielkameraden erschwert. Wer anders denkt und spricht, ausgefallene Hobbys hat oder sich ungew\u00f6hnlich verh\u00e4lt, der kann Vorbehalte ausl\u00f6sen. Um nicht ausgegrenzt zu werden, verstecken manche Kinder ihre besonderen Begabungen, Interessen und F\u00e4higkeiten. Sie passen sich den anderen Kindern an und versuchen, m\u00f6glichst unauff\u00e4llig zu bleiben. Dieser selbst auferlegte Anpassungsdruck kann sogar zu schlechten Schulnoten f\u00fchren. Manchen hochbegabten Kindern ist das lieber als ein Streberstatus.<\/p>\n<h3>Intellektuelle Unterforderung<\/h3>\n<p>Werden die intellektuellen Bed\u00fcrfnisse eines Kindes dauerhaft vernachl\u00e4ssigt, so f\u00fchrt dies zu qu\u00e4lender Langeweile und manchmal auch zu einem Gef\u00fchl der inneren Leere. In der Schule schalten diese Kinder geistig ab, wenn mehrfach derselbe Stoff erkl\u00e4rt wird oder etwas ge\u00fcbt werden soll, was l\u00e4ngst gel\u00e4ufig ist. Mitunter werden unterforderte Hochbegabte auch verhaltensauff\u00e4llig, st\u00f6ren den Unterricht und wirken somit noch weniger wie Kinder mit besten Voraussetzungen f\u00fcr Schulerfolg. Mangelt es intellektuell hochbegabten Kindern an geistigen Herausforderungen, so l\u00e4sst die schulische Motivation nach und die Leistungen entsprechen immer weniger dem, was angesichts des IQs m\u00f6glich w\u00e4re. Fachleute nennen diesen Zustand &#8222;Underachievement&#8220; (Minderleistung). Dieses Problem der mangelnden Motivation und Leistungsbereitschaft zeigt sich meist nur bei fremdbestimmten Aktivit\u00e4ten wie z.B. dem gemeinsamen Lernen im Schulunterricht. Bei eigenbestimmten Aktivit\u00e4ten in der Freizeit k\u00f6nnen hochbegabte Kinder hingegen sehr engagiert und erfolgreich sein.<\/p>\n<h2>Schulische F\u00f6rderma\u00dfnahmen f\u00fcr Hochbegabte<\/h2>\n<p>In der Schule gibt es zwei grundlegende Ma\u00dfnahmen zur F\u00f6rderung hochbegabter Sch\u00fcler: Akzeleration und Enrichment. Unter Akzeleration (Beschleunigung) wird eine fr\u00fche Einschulung und ein \u00dcberspringen von Klassen verstanden. Dieses schnellere Durchlaufen der Schullaufbahn ist Kindern anzuraten, die Gleichaltrigen intellektuell weit voraus sind und deren emotional-soziale Reife dem nicht entgegensteht. Zeigt sich die besondere Begabung eines Kindes in nur einem Fach, ist eine fachbezogene Akzeleration oder eine au\u00dferschulische F\u00f6rderung geeigneter.<\/p>\n<p>Beim Enrichment (Anreicherung) erhalten hochbegabte Sch\u00fcler zus\u00e4tzliche Lernangebote. Sie bearbeiten den Stoff des Lehrplans auf einer tieferen Ebene (vertikales Enrichment) oder sie befassen sich mit zus\u00e4tzlichen, nicht im Lehrplan stehenden Lerninhalten (horizontales Enrichment). Eine Kombination aus Akzeleration und Enrichment kann im Sinne einer heutzutage in vielen Schulen selbstverst\u00e4ndlichen Binnendifferenzierung hochbegabten Kindern eine angemessene akademische F\u00f6rderung in der Regelschule erm\u00f6glichen.<\/p>\n<h2>Wann ben\u00f6tigen hochbegabte Kinder eine Lerntherapie?<\/h2>\n<p>Lerntherapie wird meist bei Lese- und Rechtschreibschw\u00e4che (Legasthenie) oder Rechenschw\u00e4che (Dyskalkulie) in Anspruch genommen. Das ist bei hochbegabten Kindern nicht anders, denn eine hohe Intelligenz sch\u00fctzt nicht vor Teilleistungsschw\u00e4chen im Lesen, Rechtschreiben oder Rechnen. Hochbegabte nehmen neues Wissen \u00fcberwiegend beil\u00e4ufig und unstrukturiert auf. Sie punkten in den Bereichen Logik und Transferwissen, versagen aber beim Auswendiglernen und \u00dcben. Das geht meist nur in den ersten Klassen gut, wenn sich Schulerfolg so gut wie ohne Anstrengungen einstellt. Danach m\u00fcssen auch hochbegabte Kinder das Lernen lernen, sonst droht Underachievement. In einer Lerntherapie k\u00f6nnen diese Sch\u00fcler zu ihrem Denk- und Lernstil passende Lerntechniken kennen und anwenden lernen, um die durch Abschalten im Unterricht entstandenen L\u00fccken zu schlie\u00dfen und sich neuen Schulstoff strukturiert anzueignen.<\/p>\n<h2>Lerntherapeutische F\u00f6rderm\u00f6glichkeiten f\u00fcr Hochbegabte<\/h2>\n<p>In einer Lerntherapie f\u00fcr Hochbegabte m\u00fcssen Inhalte, Materialien und Lernwege gefunden werden, die zu den Interessen des Sch\u00fclers und seiner Art zu denken passen. \u00dcber Gespr\u00e4che und Beobachtungen kann eine Lerntherapeutin ein Gesp\u00fcr daf\u00fcr bekommen, unter welchen Bedingungen schulrelevantes Lernen besser gelingt. Im Bereich der Rechtschreibung haben sich regelgeleitete F\u00f6rderprogramme wie z.B. das Marburger Rechtschreibtraining bew\u00e4hrt. Bei Rechenschw\u00e4che kann kein spezielles Programm empfohlen werden, weil hier zun\u00e4chst das individuelle mathematische Denkmuster erkannt werden muss. Welche irrigen Vorstellungen f\u00fchren zu falschen Rechenergebnissen? Welche arithmetischen Basisfakten hat das hochbegabte Kind aufgrund mangelnder \u00dcbung noch nicht automatisiert? Erst nach Kl\u00e4rung dieser Fragen k\u00f6nnen F\u00f6rderziele und F\u00f6rderwege festgelegt und die passenden F\u00f6rdermaterialien ausgew\u00e4hlt werden. Bei der inhaltlichen Ausgestaltung von Lerntherapiestunden f\u00fcr Hochbegabte sind diese Grunds\u00e4tze wichtig:<\/p>\n<h2>F\u00f6rdern, aber nicht \u00fcberfordern<\/h2>\n<p>Erf\u00e4hrt eine Lerntherapeutin, dass eines ihrer Therapiekinder hochbegabt ist oder stellt sie dies selbst fest, kommt es h\u00e4ufig vor, dass sie den Schwierigkeitsgrad der \u00dcbungen im Vertrauen auf die \u00fcberdurchschnittlichen kognitiven F\u00e4higkeiten des Kindes zu hoch w\u00e4hlt. Jedoch d\u00fcrfen auch hochbegabte Kinder im Bereich ihrer Defizite nicht \u00fcberfordert werden. Ein hochbegabtes Kind mag sich sehr f\u00fcr Astronomie interessieren. Hat es eine Leseschw\u00e4che, w\u00e4re ein wissenschaftlicher Text \u00fcber die Struktur der Milchstra\u00dfe dennoch kein geeignetes Material f\u00fcr ein Lesetraining.<\/p>\n<h2>Auch an der Arbeitshaltung arbeiten<\/h2>\n<p>Neben der Vermittlung von Lernstrategien muss in einer Lerntherapie f\u00fcr Hochbegabte die Arbeitshaltung des Kindes bzw. Jugendlichen verbessert werden. Wer sich lieber mit seinen Spezialinteressen besch\u00e4ftigt und Langeweile angesichts Routineaufgaben versp\u00fcrt, vernachl\u00e4ssigt die Hefterf\u00fchrung, die Ordnung im Schulranzen und das F\u00fchren des Hausaufgabenhefts. Hier k\u00f6nnen Lerntherapeuten als Coach wirken und den hochbegabten Sch\u00fcler schrittweise zu einer g\u00fcnstigeren Arbeitshaltung f\u00fchren.<\/p>\n<h2>Dem Kind geistiges Futter bieten<\/h2>\n<p>Eine Lerntherapie kann nur erfolgreich sein, wenn sie dem Kind bzw. Jugendlichen Spa\u00df macht. Hochbegabte lieben geistiges Futter. Daher sollten Lerntherapeuten Logikr\u00e4tsel, Knobelaufgaben und kognitiv herausfordernde Spiele in die Lerntherapiestunden ihrer hochbegabten Therapiekinder integrieren. F\u00fcnf Minuten am Beginn der Stunde und f\u00fcnf Minuten am Ende sind eine lohnende Investition, denn dann wird das Kind die dazwischen liegende \u00dcbungsphase besser bew\u00e4ltigen und mit einem guten Gef\u00fchl und mit Vorfreude auf die n\u00e4chste Therapiestunde nach Hause gehen.<\/p>\n<h2>Weiterbildungen zu den Themen Hochbegabung und Lerntherapie<\/h2>\n<p>Sie m\u00f6chten mehr \u00fcber Hochbegabung und Lerntherapie erfahren, um hochbegabte Kinder besser\u00a0erkennen und f\u00f6rdern zu k\u00f6nnen? Dann empfehlen wir Ihnen den <a href=\"https:\/\/www.iflw.de\/fernstudium\/hochbegabung\/fernlehrgang_hochbegabung_fortbildung_weiterbildung.htm\">Fernstudiengang\u00a0&#8222;Hochbegabung in Theorie und Praxis&#8220;<\/a> und das <a href=\"https:\/\/www.iflw.de\/lerntherapie\/ausbildung\/lerntherapeut-ausbildung-weiterbildung-lerntherapie.htm\">Fernstudium &#8222;Integrative Lerntherapie in Theorie und Praxis&#8220;<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lesen Sie in diesem Blog-Beitrag, was unter\u00a0Hochbegabung verstanden wird, warum manche hochbegabte Kinder und Jugendliche einen\u00a0lerntherapeutischen F\u00f6rderbedarf haben und welche F\u00f6rderans\u00e4tze f\u00fcr Hochbegabte in der\u00a0Lerntherapie geeignet sind. Hochbegabte in der Lerntherapie? F\u00fcr viele ist das ein Widerspruch. Zu verbreitet ist das Bild vom\u00a0bebrillten \u00dcberflieger, der jede schulische Anforderung mit Leichtigkeit meistert und in der Freizeit\u00a0virtuos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hochbegabung"],"uagb_featured_image_src":{"full":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false],"thumbnail":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung-150x150.png",150,150,true],"medium":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false],"medium_large":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false],"large":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false],"1536x1536":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false],"2048x2048":["https:\/\/www.iflw.de\/blog\/wp-content\/uploads\/2016\/09\/Hochbegabung.png",200,200,false]},"uagb_author_info":{"display_name":"Christine Falk-Fr\u00fchbrodt, M.A.","author_link":"https:\/\/www.iflw.de\/blog\/author\/christine\/"},"uagb_comment_info":0,"uagb_excerpt":"Lesen Sie in diesem Blog-Beitrag, was unter\u00a0Hochbegabung verstanden wird, warum manche hochbegabte Kinder und Jugendliche einen\u00a0lerntherapeutischen F\u00f6rderbedarf haben und welche F\u00f6rderans\u00e4tze f\u00fcr Hochbegabte in der\u00a0Lerntherapie geeignet sind. Hochbegabte in der Lerntherapie? F\u00fcr viele ist das ein Widerspruch. Zu verbreitet ist das Bild vom\u00a0bebrillten \u00dcberflieger, der jede schulische Anforderung mit Leichtigkeit meistert und in der Freizeit\u00a0virtuos&hellip;","_links":{"self":[{"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/posts\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/comments?post=1129"}],"version-history":[{"count":0,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/posts\/1129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/media\/1868"}],"wp:attachment":[{"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/media?parent=1129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/categories?post=1129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iflw.de\/blog\/wp-json\/wp\/v2\/tags?post=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}